{"id":31508,"date":"2022-06-09T12:27:13","date_gmt":"2022-06-09T10:27:13","guid":{"rendered":"http:\/\/&amp;p=18902"},"modified":"2022-06-09T12:27:13","modified_gmt":"2022-06-09T10:27:13","slug":"premio-prof-giuseppe-grandori-anno-2021","status":"publish","type":"tribe_events","link":"https:\/\/www.dica.polimi.it\/en\/evento\/premio-prof-giuseppe-grandori-anno-2021\/","title":{"rendered":"Premio &#8220;Prof. Giuseppe Grandori&#8221; anno 2021"},"content":{"rendered":"<p>Siamo lieti di annunciare che il\u00a0<strong>24 giugno dalle ore 9.30 alle ore 12.30<\/strong>\u00a0si terr\u00e0 la cerimonia di premiazione dei vincitori del\u00a0<strong>premio \u201c<\/strong><strong>P<\/strong><strong>rof. Giuseppe Grandori\u201d<\/strong>\u00a0per le\u00a0<strong>migliori tesi\u00a0<\/strong>di dottorato\u00a0(anno 2021)\u00a0e di laurea\u00a0(anno 2020 e 2021)\u00a0su tematiche connesse alla \u201cIngegneria Sismica\u201d.<\/p>\n<p>L\u2019evento si terr\u00e0 in modalit\u00e0 mista:<\/p>\n<p>&#8211; <strong>in presenza<\/strong>: presso l&#8217;Aula Magna \u2013 Piazza Leonardo da Vinci, 32 \u2013 Edificio 1 \u2013 Primo Piano<\/p>\n<p>&#8211; <strong>online<\/strong>:\u00a0collegandosi al seguente link:<em><strong>\u00a0<a href=\"https:\/\/politecnicomilano.webex.com\/meet\/lorenza.petrini\" data-auth=\"NotApplicable\" data-linkindex=\"0\">https:\/\/politecnicomilano.webex.com\/meet\/lorenza.petrini<\/a>\u00a0<\/strong><\/em><\/p>\n<p>La mattina sar\u00e0 cos\u00ec organizzata:<\/p>\n<table style=\"height: 758px;\" width=\"1193\">\n<tbody>\n<tr>\n<td style=\"width: 588.833px;\">Saluti del vicedirettore del DICA\u00a0(Prof. Attilio Frangi)\u00a0e Presentazione dell\u2019evento\u00a0(Prof. Roberto Paolucci)<\/td>\n<td style=\"width: 588.833px;\">9.30-9.45<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 588.833px;\">Saluti della donatrice\u00a0(Prof.ssa Elisa Guagenti)\u00a0e ricordo del prof. Grandori\u00a0(Prof.ssa Elsa Garavaglia)<\/td>\n<td style=\"width: 588.833px;\">9.45-10.15<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 588.833px;\">Presentazione delle tesi di dottorato vincitrici:<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Luca Capacci<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Alban Kita<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Lucia Minnucci<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Satyadhrik Sharma<\/td>\n<td style=\"width: 588.833px;\">10.15-11.30<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 588.833px;\">Presentazione delle tesi di laurea vincitrici:<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Claudio Manuel Ascunce Lopez<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Victor Moises Hernandez Aguirre<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Matteo Maria Messore<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Marco Vittone<\/td>\n<td style=\"width: 588.833px;\">11.30-12.00<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 588.833px;\">Saluti conclusivi<\/td>\n<td style=\"width: 588.833px;\">12.00-12.15<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Siamo lieti di annunciare che il\u00a024 giugno dalle ore 9.30 alle ore 12.30\u00a0si terr\u00e0 la cerimonia di premiazione dei vincitori del\u00a0premio \u201cProf. Giuseppe Grandori\u201d\u00a0per le\u00a0migliori tesi\u00a0di dottorato\u00a0(anno 2021)\u00a0e di laurea\u00a0(anno&#8230;<\/p>","protected":false},"author":6,"featured_media":18917,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[1565,1566],"tribe_events_cat":[930],"class_list":["post-31508","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-premiazione-tesi","tag-premio-prof-giuseppe-grandori","tribe_events_cat-seminari","cat_seminari"],"acf":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.dica.polimi.it\/en\/wp-json\/wp\/v2\/tribe_events\/31508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dica.polimi.it\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.dica.polimi.it\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.dica.polimi.it\/en\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":0,"href":"https:\/\/www.dica.polimi.it\/en\/wp-json\/wp\/v2\/tribe_events\/31508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dica.polimi.it\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.dica.polimi.it\/en\/wp-json\/wp\/v2\/media?parent=31508"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dica.polimi.it\/en\/wp-json\/wp\/v2\/tags?post=31508"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.dica.polimi.it\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=31508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}